{"id":724,"date":"2011-06-23T08:42:11","date_gmt":"2011-06-22T23:42:11","guid":{"rendered":"http:\/\/www.mikipaint.co.jp\/?p=724"},"modified":"2011-06-23T08:42:11","modified_gmt":"2011-06-22T23:42:11","slug":"gt%e3%83%90%e3%83%95%e3%82%ab%e3%82%bf%e3%83%ad%e3%82%b0%e6%9b%b4%e6%96%b0","status":"publish","type":"post","link":"https:\/\/mikipaint.co.jp\/mp\/gt%e3%83%90%e3%83%95%e3%82%ab%e3%82%bf%e3%83%ad%e3%82%b0%e6%9b%b4%e6%96%b0\/","title":{"rendered":"G&#038;T\u30d0\u30d5\u30ab\u30bf\u30ed\u30b0\u66f4\u65b0"},"content":{"rendered":"<p>\u30ea\u30a2\u30eb\u30ab\u30c3\u30c8\u30b3\u30f3\u30d1\u30a6\u30f3\u30c9\u304c\u597d\u8a55\u306eG&#038;T\u793e\u3002<br \/>\n\u4eca\u56de\u3001\u30df\u30cb\u30dd\u30ea\u30b7\u30e3\u30fc\u7528\u30d0\u30d5\u304c\u65b0\u767b\u5834\u3002<br \/>\n\u3053\u308c\u306b\u5408\u308f\u305b\u3066\u30ab\u30bf\u30ed\u30b0\u3082\u4e00\u65b0\u3057\u307e\u3057\u305f\u3002<\/p>\n<p><a href=\"https:\/\/mikipaint.co.jp\/mp\/pdf\/gtpolish.pdf\">\uff27\uff34\u30dd\u30ea\u30c3\u30b7\u30f3\u30b0\u30d1\u30f3\u30d5<\/a><br \/>\n<a href=\"https:\/\/mikipaint.co.jp\/mp\/pdf\/gtbuff.pdf\">\uff27\uff34\u30d0\u30d5\u30ab\u30bf\u30ed\u30b0<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u30ea\u30a2\u30eb\u30ab\u30c3\u30c8\u30b3\u30f3\u30d1\u30a6\u30f3\u30c9\u304c\u597d\u8a55\u306eG&#038;T\u793e\u3002 \u4eca\u56de\u3001\u30df\u30cb\u30dd\u30ea\u30b7\u30e3\u30fc\u7528\u30d0\u30d5\u304c\u65b0\u767b\u5834\u3002 \u3053\u308c\u306b\u5408\u308f\u305b\u3066\u30ab\u30bf\u30ed\u30b0\u3082\u4e00\u65b0\u3057\u307e\u3057\u305f\u3002 \uff27\uff34\u30dd\u30ea\u30c3\u30b7\u30f3\u30b0\u30d1\u30f3\u30d5 \uff27\uff34\u30d0\u30d5\u30ab\u30bf\u30ed\u30b0<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"swell_btn_cv_data":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-724","post","type-post","status-publish","format-standard","hentry","category-tools"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:35:47","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/mikipaint.co.jp\/mp\/wp-json\/wp\/v2\/posts\/724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mikipaint.co.jp\/mp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mikipaint.co.jp\/mp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mikipaint.co.jp\/mp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mikipaint.co.jp\/mp\/wp-json\/wp\/v2\/comments?post=724"}],"version-history":[{"count":1,"href":"https:\/\/mikipaint.co.jp\/mp\/wp-json\/wp\/v2\/posts\/724\/revisions"}],"predecessor-version":[{"id":725,"href":"https:\/\/mikipaint.co.jp\/mp\/wp-json\/wp\/v2\/posts\/724\/revisions\/725"}],"wp:attachment":[{"href":"https:\/\/mikipaint.co.jp\/mp\/wp-json\/wp\/v2\/media?parent=724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mikipaint.co.jp\/mp\/wp-json\/wp\/v2\/categories?post=724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mikipaint.co.jp\/mp\/wp-json\/wp\/v2\/tags?post=724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}